{"id":2689,"date":"2024-12-26T16:10:52","date_gmt":"2024-12-26T15:10:52","guid":{"rendered":"https:\/\/www.forest-hill.fr\/blockbuster-forest-hill-fete-ses-1-an-dexistence-loffre-escalade-ne-cesse-de-grimper-en-ile-de-france\/"},"modified":"2025-02-24T11:22:19","modified_gmt":"2025-02-24T10:22:19","slug":"blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france","status":"publish","type":"post","link":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/","title":{"rendered":"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":1786,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France - Forest Hill<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France - Forest Hill\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Forest Hill\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ForestHill.fb\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-26T15:10:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T10:22:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/317603423_117999167795139_5488675519542958131_n-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maroua.s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clubsforesthill\" \/>\n<meta name=\"twitter:site\" content=\"@clubsforesthill\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"maroua.s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/\"},\"author\":{\"name\":\"maroua.s\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#\\\/schema\\\/person\\\/0d3343eb5a1d0a3793176e47c5431def\"},\"headline\":\"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France\",\"datePublished\":\"2024-12-26T15:10:52+00:00\",\"dateModified\":\"2025-02-24T10:22:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forest-hill.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/317603423_117999167795139_5488675519542958131_n-1.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/\",\"url\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/\",\"name\":\"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France - Forest Hill\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forest-hill.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/317603423_117999167795139_5488675519542958131_n-1.jpg\",\"datePublished\":\"2024-12-26T15:10:52+00:00\",\"dateModified\":\"2025-02-24T10:22:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forest-hill.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/317603423_117999167795139_5488675519542958131_n-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forest-hill.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/317603423_117999167795139_5488675519542958131_n-1.jpg\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/\",\"name\":\"Forest Hill\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#organization\",\"name\":\"Forest Hill\",\"url\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forest-hill.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo_Forest-Hill.svg\",\"contentUrl\":\"https:\\\/\\\/www.forest-hill.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo_Forest-Hill.svg\",\"width\":1,\"height\":1,\"caption\":\"Forest Hill\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ForestHill.fb\\\/\",\"https:\\\/\\\/x.com\\\/clubsforesthill\",\"https:\\\/\\\/www.instagram.com\\\/clubsforesthill\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forest-hill.fr\\\/en\\\/#\\\/schema\\\/person\\\/0d3343eb5a1d0a3793176e47c5431def\",\"name\":\"maroua.s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfa2446fe38d70f26cc1dd2d8621593720a3b7d5f0ea2bc0bcca8ee098d215dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfa2446fe38d70f26cc1dd2d8621593720a3b7d5f0ea2bc0bcca8ee098d215dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfa2446fe38d70f26cc1dd2d8621593720a3b7d5f0ea2bc0bcca8ee098d215dd?s=96&d=mm&r=g\",\"caption\":\"maroua.s\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France - Forest Hill","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/","og_locale":"en_US","og_type":"article","og_title":"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France - Forest Hill","og_url":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/","og_site_name":"Forest Hill","article_publisher":"https:\/\/www.facebook.com\/ForestHill.fb\/","article_published_time":"2024-12-26T15:10:52+00:00","article_modified_time":"2025-02-24T10:22:19+00:00","og_image":[{"width":2048,"height":2048,"url":"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/317603423_117999167795139_5488675519542958131_n-1.jpg","type":"image\/jpeg"}],"author":"maroua.s","twitter_card":"summary_large_image","twitter_creator":"@clubsforesthill","twitter_site":"@clubsforesthill","twitter_misc":{"Written by":"maroua.s","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/#article","isPartOf":{"@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/"},"author":{"name":"maroua.s","@id":"https:\/\/www.forest-hill.fr\/en\/#\/schema\/person\/0d3343eb5a1d0a3793176e47c5431def"},"headline":"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France","datePublished":"2024-12-26T15:10:52+00:00","dateModified":"2025-02-24T10:22:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/"},"wordCount":15,"publisher":{"@id":"https:\/\/www.forest-hill.fr\/en\/#organization"},"image":{"@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/317603423_117999167795139_5488675519542958131_n-1.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/","url":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/","name":"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France - Forest Hill","isPartOf":{"@id":"https:\/\/www.forest-hill.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/#primaryimage"},"image":{"@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/317603423_117999167795139_5488675519542958131_n-1.jpg","datePublished":"2024-12-26T15:10:52+00:00","dateModified":"2025-02-24T10:22:19+00:00","breadcrumb":{"@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/#primaryimage","url":"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/317603423_117999167795139_5488675519542958131_n-1.jpg","contentUrl":"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/317603423_117999167795139_5488675519542958131_n-1.jpg","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.forest-hill.fr\/en\/blockbuster-forest-hill-celebrates-its-1st-anniversary-the-climbing-offer-continues-to-rise-in-ile-de-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.forest-hill.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Blockbuster Forest Hill celebrates its 1st anniversary : the climbing offer continues to rise in \u00cele-de-France"}]},{"@type":"WebSite","@id":"https:\/\/www.forest-hill.fr\/en\/#website","url":"https:\/\/www.forest-hill.fr\/en\/","name":"Forest Hill","description":"","publisher":{"@id":"https:\/\/www.forest-hill.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forest-hill.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.forest-hill.fr\/en\/#organization","name":"Forest Hill","url":"https:\/\/www.forest-hill.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.forest-hill.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/Logo_Forest-Hill.svg","contentUrl":"https:\/\/www.forest-hill.fr\/wp-content\/uploads\/2024\/09\/Logo_Forest-Hill.svg","width":1,"height":1,"caption":"Forest Hill"},"image":{"@id":"https:\/\/www.forest-hill.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ForestHill.fb\/","https:\/\/x.com\/clubsforesthill","https:\/\/www.instagram.com\/clubsforesthill\/"]},{"@type":"Person","@id":"https:\/\/www.forest-hill.fr\/en\/#\/schema\/person\/0d3343eb5a1d0a3793176e47c5431def","name":"maroua.s","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cfa2446fe38d70f26cc1dd2d8621593720a3b7d5f0ea2bc0bcca8ee098d215dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cfa2446fe38d70f26cc1dd2d8621593720a3b7d5f0ea2bc0bcca8ee098d215dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa2446fe38d70f26cc1dd2d8621593720a3b7d5f0ea2bc0bcca8ee098d215dd?s=96&d=mm&r=g","caption":"maroua.s"}}]}},"_links":{"self":[{"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/posts\/2689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/comments?post=2689"}],"version-history":[{"count":3,"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/posts\/2689\/revisions"}],"predecessor-version":[{"id":2692,"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/posts\/2689\/revisions\/2692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/media\/1786"}],"wp:attachment":[{"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/media?parent=2689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/categories?post=2689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forest-hill.fr\/en\/wp-json\/wp\/v2\/tags?post=2689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}